{"id":1,"name":"Enfeite Decora","url":"https:\/\/enfeitedecora.com\/stories","description":"O Enfeitedecora \u00e9 uma plataforma de conte\u00fado especializado dedicada a traduzir o universo da arquitetura, do design de interiores e do paisagismo em solu\u00e7\u00f5es pr\u00e1ticas e inspiradoras. O projeto \u00e9 idealizado e fundado por Cl\u00e1udio P. Filla e realizado pela Editora CFILLA (CNPJ: 47.923.569\/0001-92).\r\n\r\nNossa Lideran\u00e7a e Vis\u00e3o Multidisciplinar Com quase 11 anos de experi\u00eancia no mercado de comunica\u00e7\u00e3o e m\u00eddias digitais, Cl\u00e1udio P. Filla atua como Editor-chefe e Estrategista de Conte\u00fado. Sua trajet\u00f3ria inclui a reda\u00e7\u00e3o especializada em portais de relev\u00e2ncia nacional, como o Agro na M\u00eddia, o que confere ao Enfeitedecora uma vis\u00e3o multidisciplinar \u00fanica: a uni\u00e3o entre o conhecimento t\u00e9cnico do setor produtivo e paisag\u00edstico com a sofistica\u00e7\u00e3o do design urbano.","link":"https:\/\/enfeitedecora.com\/stories\/author\/enfeitedecoraadm\/","slug":"enfeitedecoraadm","avatar_urls":{"24":"https:\/\/enfeitedecora.com\/stories\/wp-content\/litespeed\/avatar\/8ba8109395ab7a8883128ec86d4ba68b.jpg?ver=1778090074","48":"https:\/\/enfeitedecora.com\/stories\/wp-content\/litespeed\/avatar\/371d15d447cca3e37c1df4db74bcf442.jpg?ver=1778090074","96":"https:\/\/enfeitedecora.com\/stories\/wp-content\/litespeed\/avatar\/f3bcdc045383ee3c85d2910fa25676a0.jpg?ver=1778088833"},"meta":{"web_stories_tracking_optin":false,"web_stories_media_optimization":true,"web_stories_onboarding":{"safeZone":true}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Enfeite Decora, Autor em Stories | Enfeite Decora<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/enfeitedecora.com\/stories\/author\/enfeitedecoraadm\/\" \/>\n<meta property=\"og:locale\" content=\"pt_BR\" \/>\n<meta property=\"og:type\" content=\"profile\" \/>\n<meta property=\"og:title\" content=\"Enfeite Decora, Autor em Stories | Enfeite Decora\" \/>\n<meta property=\"og:url\" content=\"https:\/\/enfeitedecora.com\/stories\/author\/enfeitedecoraadm\/\" \/>\n<meta property=\"og:site_name\" content=\"Stories | Enfeite Decora\" \/>\n<meta property=\"og:image\" content=\"https:\/\/enfeitedecora.com\/stories\/wp-content\/litespeed\/avatar\/251c1bd4eecdd1b9a227b8391c0601f6.jpg?ver=1774670345\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"ProfilePage\",\"@id\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/author\\\/enfeitedecoraadm\\\/\",\"url\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/author\\\/enfeitedecoraadm\\\/\",\"name\":\"Enfeite Decora, Autor em Stories | Enfeite Decora\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/author\\\/enfeitedecoraadm\\\/#breadcrumb\"},\"inLanguage\":\"pt-BR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/author\\\/enfeitedecoraadm\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/author\\\/enfeitedecoraadm\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"In\u00edcio\",\"item\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Arquivos para Enfeite Decora\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/#website\",\"url\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/\",\"name\":\"Stories | Enfeite Decora\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"pt-BR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/#organization\",\"name\":\"Enfeite Decora\",\"url\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Logo_1614472736542_1614473478595_2-removebg-preview.png\",\"contentUrl\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/Logo_1614472736542_1614473478595_2-removebg-preview.png\",\"width\":498,\"height\":501,\"caption\":\"Enfeite Decora\"},\"image\":{\"@id\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/facebook.com\\\/enfeitedecora\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/#\\\/schema\\\/person\\\/9b0d820009848f2d495963fd1e1d84ca\",\"name\":\"Enfeite Decora\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"pt-BR\",\"@id\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/wp-content\\\/litespeed\\\/avatar\\\/f3bcdc045383ee3c85d2910fa25676a0.jpg?ver=1778088833\",\"url\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/wp-content\\\/litespeed\\\/avatar\\\/f3bcdc045383ee3c85d2910fa25676a0.jpg?ver=1778088833\",\"contentUrl\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/wp-content\\\/litespeed\\\/avatar\\\/f3bcdc045383ee3c85d2910fa25676a0.jpg?ver=1778088833\",\"caption\":\"Enfeite Decora\"},\"description\":\"O Enfeitedecora \u00e9 uma plataforma de conte\u00fado especializado dedicada a traduzir o universo da arquitetura, do design de interiores e do paisagismo em solu\u00e7\u00f5es pr\u00e1ticas e inspiradoras. O projeto \u00e9 idealizado e fundado por Cl\u00e1udio P. Filla e realizado pela Editora CFILLA (CNPJ: 47.923.569\\\/0001-92). Nossa Lideran\u00e7a e Vis\u00e3o Multidisciplinar Com quase 11 anos de experi\u00eancia no mercado de comunica\u00e7\u00e3o e m\u00eddias digitais, Cl\u00e1udio P. Filla atua como Editor-chefe e Estrategista de Conte\u00fado. Sua trajet\u00f3ria inclui a reda\u00e7\u00e3o especializada em portais de relev\u00e2ncia nacional, como o Agro na M\u00eddia, o que confere ao Enfeitedecora uma vis\u00e3o multidisciplinar \u00fanica: a uni\u00e3o entre o conhecimento t\u00e9cnico do setor produtivo e paisag\u00edstico com a sofistica\u00e7\u00e3o do design urbano.\",\"sameAs\":[\"https:\\\/\\\/enfeitedecora.com\\\/stories\"],\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/enfeitedecora.com\\\/stories\\\/author\\\/enfeitedecoraadm\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Enfeite Decora, Autor em Stories | Enfeite Decora","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/enfeitedecora.com\/stories\/author\/enfeitedecoraadm\/","og_locale":"pt_BR","og_type":"profile","og_title":"Enfeite Decora, Autor em Stories | Enfeite Decora","og_url":"https:\/\/enfeitedecora.com\/stories\/author\/enfeitedecoraadm\/","og_site_name":"Stories | Enfeite Decora","og_image":[{"url":"https:\/\/enfeitedecora.com\/stories\/wp-content\/litespeed\/avatar\/251c1bd4eecdd1b9a227b8391c0601f6.jpg?ver=1774670345","type":"","width":"","height":""}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"ProfilePage","@id":"https:\/\/enfeitedecora.com\/stories\/author\/enfeitedecoraadm\/","url":"https:\/\/enfeitedecora.com\/stories\/author\/enfeitedecoraadm\/","name":"Enfeite Decora, Autor em Stories | Enfeite Decora","isPartOf":{"@id":"https:\/\/enfeitedecora.com\/stories\/#website"},"breadcrumb":{"@id":"https:\/\/enfeitedecora.com\/stories\/author\/enfeitedecoraadm\/#breadcrumb"},"inLanguage":"pt-BR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/enfeitedecora.com\/stories\/author\/enfeitedecoraadm\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/enfeitedecora.com\/stories\/author\/enfeitedecoraadm\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"In\u00edcio","item":"https:\/\/enfeitedecora.com\/stories\/"},{"@type":"ListItem","position":2,"name":"Arquivos para Enfeite Decora"}]},{"@type":"WebSite","@id":"https:\/\/enfeitedecora.com\/stories\/#website","url":"https:\/\/enfeitedecora.com\/stories\/","name":"Stories | Enfeite Decora","description":"","publisher":{"@id":"https:\/\/enfeitedecora.com\/stories\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/enfeitedecora.com\/stories\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"pt-BR"},{"@type":"Organization","@id":"https:\/\/enfeitedecora.com\/stories\/#organization","name":"Enfeite Decora","url":"https:\/\/enfeitedecora.com\/stories\/","logo":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/enfeitedecora.com\/stories\/#\/schema\/logo\/image\/","url":"https:\/\/enfeitedecora.com\/stories\/wp-content\/uploads\/2025\/10\/Logo_1614472736542_1614473478595_2-removebg-preview.png","contentUrl":"https:\/\/enfeitedecora.com\/stories\/wp-content\/uploads\/2025\/10\/Logo_1614472736542_1614473478595_2-removebg-preview.png","width":498,"height":501,"caption":"Enfeite Decora"},"image":{"@id":"https:\/\/enfeitedecora.com\/stories\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/facebook.com\/enfeitedecora"]},{"@type":"Person","@id":"https:\/\/enfeitedecora.com\/stories\/#\/schema\/person\/9b0d820009848f2d495963fd1e1d84ca","name":"Enfeite Decora","image":{"@type":"ImageObject","inLanguage":"pt-BR","@id":"https:\/\/enfeitedecora.com\/stories\/wp-content\/litespeed\/avatar\/f3bcdc045383ee3c85d2910fa25676a0.jpg?ver=1778088833","url":"https:\/\/enfeitedecora.com\/stories\/wp-content\/litespeed\/avatar\/f3bcdc045383ee3c85d2910fa25676a0.jpg?ver=1778088833","contentUrl":"https:\/\/enfeitedecora.com\/stories\/wp-content\/litespeed\/avatar\/f3bcdc045383ee3c85d2910fa25676a0.jpg?ver=1778088833","caption":"Enfeite Decora"},"description":"O Enfeitedecora \u00e9 uma plataforma de conte\u00fado especializado dedicada a traduzir o universo da arquitetura, do design de interiores e do paisagismo em solu\u00e7\u00f5es pr\u00e1ticas e inspiradoras. O projeto \u00e9 idealizado e fundado por Cl\u00e1udio P. Filla e realizado pela Editora CFILLA (CNPJ: 47.923.569\/0001-92). Nossa Lideran\u00e7a e Vis\u00e3o Multidisciplinar Com quase 11 anos de experi\u00eancia no mercado de comunica\u00e7\u00e3o e m\u00eddias digitais, Cl\u00e1udio P. Filla atua como Editor-chefe e Estrategista de Conte\u00fado. Sua trajet\u00f3ria inclui a reda\u00e7\u00e3o especializada em portais de relev\u00e2ncia nacional, como o Agro na M\u00eddia, o que confere ao Enfeitedecora uma vis\u00e3o multidisciplinar \u00fanica: a uni\u00e3o entre o conhecimento t\u00e9cnico do setor produtivo e paisag\u00edstico com a sofistica\u00e7\u00e3o do design urbano.","sameAs":["https:\/\/enfeitedecora.com\/stories"],"mainEntityOfPage":{"@id":"https:\/\/enfeitedecora.com\/stories\/author\/enfeitedecoraadm\/"}}]}},"_links":{"self":[{"href":"https:\/\/enfeitedecora.com\/stories\/wp-json\/wp\/v2\/users\/1","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/enfeitedecora.com\/stories\/wp-json\/wp\/v2\/users"}]}}